{"id":1023,"count":8,"description":"","link":"https:\/\/www.mentaymora.com\/index.php\/categoria-producto\/navidad\/para-decorar\/","name":"PARA DECORAR","slug":"para-decorar","taxonomy":"product_cat","parent":1187,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PARA DECORAR de Navidad personalizadas - Menta y Mora - Tienda<\/title>\n<meta name=\"description\" content=\"Poner una nota de color en tu \u00e1rbol de Navidad este a\u00f1o va a ser muy f\u00e1cil, se la puedes regalar a esa persona preferida, o incluso poner en la puerta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mentaymora.com\/index.php\/categoria-producto\/navidad\/para-decorar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PARA DECORAR de Navidad personalizadas - Menta y Mora - Tienda\" \/>\n<meta property=\"og:description\" content=\"Poner una nota de color en tu \u00e1rbol de Navidad este a\u00f1o va a ser muy f\u00e1cil, se la puedes regalar a esa persona preferida, o incluso poner en la puerta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mentaymora.com\/index.php\/categoria-producto\/navidad\/para-decorar\/\" \/>\n<meta property=\"og:site_name\" content=\"Menta y Mora\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.mentaymora.com\\\/index.php\\\/categoria-producto\\\/navidad\\\/para-decorar\\\/\",\"url\":\"https:\\\/\\\/www.mentaymora.com\\\/index.php\\\/categoria-producto\\\/navidad\\\/para-decorar\\\/\",\"name\":\"PARA DECORAR de Navidad personalizadas - Menta y Mora - Tienda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mentaymora.com\\\/#website\"},\"description\":\"Poner una nota de color en tu \u00e1rbol de Navidad este a\u00f1o va a ser muy f\u00e1cil, se la puedes regalar a esa persona preferida, o incluso poner en la puerta.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mentaymora.com\\\/index.php\\\/categoria-producto\\\/navidad\\\/para-decorar\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mentaymora.com\\\/index.php\\\/categoria-producto\\\/navidad\\\/para-decorar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mentaymora.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NAVIDAD\",\"item\":\"https:\\\/\\\/www.mentaymora.com\\\/index.php\\\/categoria-producto\\\/navidad\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PARA DECORAR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mentaymora.com\\\/#website\",\"url\":\"https:\\\/\\\/www.mentaymora.com\\\/\",\"name\":\"Menta y Mora\",\"description\":\"Regalos y Complementos\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mentaymora.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mentaymora.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mentaymora.com\\\/#organization\",\"name\":\"Menta y Mora\",\"url\":\"https:\\\/\\\/www.mentaymora.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mentaymora.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mentaymora.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mentaymora.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo.jpg\",\"width\":1172,\"height\":1172,\"caption\":\"Menta y Mora\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mentaymora.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-es.facebook.com\\\/MentayMora\\\/\",\"https:\\\/\\\/www.instagram.com\\\/mentaymora.illescas\\\/?hl=es\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCuMMtdck_1XS-MyW6ZnBAlw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PARA DECORAR de Navidad personalizadas - Menta y Mora - Tienda","description":"Poner una nota de color en tu \u00e1rbol de Navidad este a\u00f1o va a ser muy f\u00e1cil, se la puedes regalar a esa persona preferida, o incluso poner en la puerta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mentaymora.com\/index.php\/categoria-producto\/navidad\/para-decorar\/","og_locale":"es_ES","og_type":"article","og_title":"PARA DECORAR de Navidad personalizadas - Menta y Mora - Tienda","og_description":"Poner una nota de color en tu \u00e1rbol de Navidad este a\u00f1o va a ser muy f\u00e1cil, se la puedes regalar a esa persona preferida, o incluso poner en la puerta.","og_url":"https:\/\/www.mentaymora.com\/index.php\/categoria-producto\/navidad\/para-decorar\/","og_site_name":"Menta y Mora","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.mentaymora.com\/index.php\/categoria-producto\/navidad\/para-decorar\/","url":"https:\/\/www.mentaymora.com\/index.php\/categoria-producto\/navidad\/para-decorar\/","name":"PARA DECORAR de Navidad personalizadas - Menta y Mora - Tienda","isPartOf":{"@id":"https:\/\/www.mentaymora.com\/#website"},"description":"Poner una nota de color en tu \u00e1rbol de Navidad este a\u00f1o va a ser muy f\u00e1cil, se la puedes regalar a esa persona preferida, o incluso poner en la puerta.","breadcrumb":{"@id":"https:\/\/www.mentaymora.com\/index.php\/categoria-producto\/navidad\/para-decorar\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mentaymora.com\/index.php\/categoria-producto\/navidad\/para-decorar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mentaymora.com\/"},{"@type":"ListItem","position":2,"name":"NAVIDAD","item":"https:\/\/www.mentaymora.com\/index.php\/categoria-producto\/navidad\/"},{"@type":"ListItem","position":3,"name":"PARA DECORAR"}]},{"@type":"WebSite","@id":"https:\/\/www.mentaymora.com\/#website","url":"https:\/\/www.mentaymora.com\/","name":"Menta y Mora","description":"Regalos y Complementos","publisher":{"@id":"https:\/\/www.mentaymora.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mentaymora.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mentaymora.com\/#organization","name":"Menta y Mora","url":"https:\/\/www.mentaymora.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mentaymora.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.mentaymora.com\/wp-content\/uploads\/2021\/07\/Logo.jpg","contentUrl":"https:\/\/www.mentaymora.com\/wp-content\/uploads\/2021\/07\/Logo.jpg","width":1172,"height":1172,"caption":"Menta y Mora"},"image":{"@id":"https:\/\/www.mentaymora.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-es.facebook.com\/MentayMora\/","https:\/\/www.instagram.com\/mentaymora.illescas\/?hl=es","https:\/\/www.youtube.com\/channel\/UCuMMtdck_1XS-MyW6ZnBAlw"]}]}},"_links":{"self":[{"href":"https:\/\/www.mentaymora.com\/index.php\/wp-json\/wp\/v2\/product_cat\/1023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mentaymora.com\/index.php\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.mentaymora.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.mentaymora.com\/index.php\/wp-json\/wp\/v2\/product_cat\/1187"}],"wp:post_type":[{"href":"https:\/\/www.mentaymora.com\/index.php\/wp-json\/wp\/v2\/product?product_cat=1023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}